{"id":3883,"date":"2024-03-15T15:37:47","date_gmt":"2024-03-15T13:37:47","guid":{"rendered":"https:\/\/trialoog.taltech.ee\/?post_type=writer&#038;p=3883"},"modified":"2024-05-02T12:31:39","modified_gmt":"2024-05-02T10:31:39","slug":"eliis-salm","status":"publish","type":"writer","link":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/","title":{"rendered":"Eliis Salm"},"featured_media":3657,"template":"","class_list":["post-3883","writer","type-writer","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eliis Salm - Trialoog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eliis Salm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/\" \/>\n<meta property=\"og:site_name\" content=\"Trialoog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=61555592234506\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-02T10:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/03\/Eliis-Salm.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1073\" \/>\n\t<meta property=\"og:image:height\" content=\"955\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/\",\"name\":\"Eliis Salm - Trialoog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Eliis-Salm.jpg\",\"datePublished\":\"2024-03-15T13:37:47+00:00\",\"dateModified\":\"2024-05-02T10:31:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/#primaryimage\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Eliis-Salm.jpg\",\"contentUrl\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/Eliis-Salm.jpg\",\"width\":1073,\"height\":955,\"caption\":\"Eliis Salm | Erakogu\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/copywriter\\\/eliis-salm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eliis Salm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\",\"name\":\"Trialoog\",\"description\":\"Entrepreneurship and science portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#organization\"},\"alternateName\":\"Trialoog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#organization\",\"name\":\"Tallinna Tehnika\u00fclikool\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trialoog-logo-tumesinine-hall.svg\",\"contentUrl\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trialoog-logo-tumesinine-hall.svg\",\"width\":342,\"height\":87,\"caption\":\"Tallinna Tehnika\u00fclikool\"},\"image\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61555592234506\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/trialoog-taltech\\\/about\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eliis Salm - Trialoog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/","og_locale":"en_US","og_type":"article","og_title":"Eliis Salm","og_url":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/","og_site_name":"Trialoog","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=61555592234506","article_modified_time":"2024-05-02T10:31:39+00:00","og_image":[{"width":1073,"height":955,"url":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/03\/Eliis-Salm.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/","url":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/","name":"Eliis Salm - Trialoog","isPartOf":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/#primaryimage"},"image":{"@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/#primaryimage"},"thumbnailUrl":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/03\/Eliis-Salm.jpg","datePublished":"2024-03-15T13:37:47+00:00","dateModified":"2024-05-02T10:31:39+00:00","breadcrumb":{"@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/#primaryimage","url":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/03\/Eliis-Salm.jpg","contentUrl":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/03\/Eliis-Salm.jpg","width":1073,"height":955,"caption":"Eliis Salm | Erakogu"},{"@type":"BreadcrumbList","@id":"https:\/\/trialoog.taltech.ee\/en\/copywriter\/eliis-salm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trialoog.taltech.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Eliis Salm"}]},{"@type":"WebSite","@id":"https:\/\/trialoog.taltech.ee\/en\/#website","url":"https:\/\/trialoog.taltech.ee\/en\/","name":"Trialoog","description":"Entrepreneurship and science portal","publisher":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#organization"},"alternateName":"Trialoog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trialoog.taltech.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/trialoog.taltech.ee\/en\/#organization","name":"Tallinna Tehnika\u00fclikool","url":"https:\/\/trialoog.taltech.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trialoog.taltech.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/02\/trialoog-logo-tumesinine-hall.svg","contentUrl":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/02\/trialoog-logo-tumesinine-hall.svg","width":342,"height":87,"caption":"Tallinna Tehnika\u00fclikool"},"image":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61555592234506","https:\/\/www.linkedin.com\/showcase\/trialoog-taltech\/about\/"]}]}},"_links":{"self":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/writer\/3883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/writer"}],"about":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/types\/writer"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/media\/3657"}],"wp:attachment":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/media?parent=3883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}