{"id":472,"count":3,"description":"","link":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/","name":"tehnoloogia","slug":"tehnoloogia-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>tehnoloogia Archives - Trialoog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tehnoloogia Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Trialoog\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/tag\\\/tehnoloogia-en\\\/\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/tag\\\/tehnoloogia-en\\\/\",\"name\":\"tehnoloogia Archives - Trialoog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/tag\\\/tehnoloogia-en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/tag\\\/tehnoloogia-en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tehnoloogia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\",\"name\":\"Trialoog\",\"description\":\"Entrepreneurship and science portal\",\"publisher\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#organization\"},\"alternateName\":\"Trialoog\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#organization\",\"name\":\"Tallinna Tehnika\u00fclikool\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trialoog-logo-tumesinine-hall.svg\",\"contentUrl\":\"https:\\\/\\\/trialoog.taltech.ee\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/trialoog-logo-tumesinine-hall.svg\",\"width\":342,\"height\":87,\"caption\":\"Tallinna Tehnika\u00fclikool\"},\"image\":{\"@id\":\"https:\\\/\\\/trialoog.taltech.ee\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=61555592234506\",\"https:\\\/\\\/www.linkedin.com\\\/showcase\\\/trialoog-taltech\\\/about\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"tehnoloogia Archives - Trialoog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/","og_locale":"en_US","og_type":"article","og_title":"tehnoloogia Archives","og_url":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/","og_site_name":"Trialoog","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/","url":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/","name":"tehnoloogia Archives - Trialoog","isPartOf":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#website"},"breadcrumb":{"@id":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/trialoog.taltech.ee\/en\/tag\/tehnoloogia-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/trialoog.taltech.ee\/en\/"},{"@type":"ListItem","position":2,"name":"tehnoloogia"}]},{"@type":"WebSite","@id":"https:\/\/trialoog.taltech.ee\/en\/#website","url":"https:\/\/trialoog.taltech.ee\/en\/","name":"Trialoog","description":"Entrepreneurship and science portal","publisher":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#organization"},"alternateName":"Trialoog","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/trialoog.taltech.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/trialoog.taltech.ee\/en\/#organization","name":"Tallinna Tehnika\u00fclikool","url":"https:\/\/trialoog.taltech.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/trialoog.taltech.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/02\/trialoog-logo-tumesinine-hall.svg","contentUrl":"https:\/\/trialoog.taltech.ee\/wp-content\/uploads\/2024\/02\/trialoog-logo-tumesinine-hall.svg","width":342,"height":87,"caption":"Tallinna Tehnika\u00fclikool"},"image":{"@id":"https:\/\/trialoog.taltech.ee\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=61555592234506","https:\/\/www.linkedin.com\/showcase\/trialoog-taltech\/about\/"]}]}},"_links":{"self":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/tags\/472","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/trialoog.taltech.ee\/en\/wp-json\/wp\/v2\/posts?tags=472"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}